{"id":1083,"date":"2022-07-20T14:41:31","date_gmt":"2022-07-20T13:41:31","guid":{"rendered":"https:\/\/kingfisherlub.wordifysites.com\/product\/high-pressure-leak-proof-22mm-diameter-button-head-113mm-long-m16-x-1-5-thread-with-relief-slot\/"},"modified":"2026-07-08T11:08:40","modified_gmt":"2026-07-08T10:08:40","slug":"testa-a-bottone-a-prova-di-perdite-ad-alta-pressione-diametro-22-mm-lunghezza-113-mm-filettatura-m16-x-15-con-fessura-di-scarico","status":"publish","type":"product","link":"https:\/\/kingfisherlubrication.co.uk\/it\/product\/high-pressure-leak-proof-22mm-diameter-button-head-113mm-long-m16-x-1-5-thread-with-relief-slot\/","title":{"rendered":"Testa a bottone a prova di perdite ad alta pressione, diametro 22 mm, lunghezza 113 mm, filettatura M16 x 1,5 con fessura di scarico"},"content":{"rendered":"<p>TRASPORTO \u2013 Un cappuccio protettivo in nylon \u00e8 montato sulla filettatura M16 e l&#039;unit\u00e0 completa \u00e8 imballata in una custodia in rete di nylon per una maggiore protezione durante il trasporto.<\/p>\n<p>GUARNIZIONI \u2013 Questo raccordo a testa tonda \u00e8 dotato di una valvola di ritegno in acciaio e di un o-ring in nitrile, una molla resistente alle sollecitazioni e un o-ring in nitrile sigilla l&#039;unit\u00e0 a testa tonda all&#039;adattatore esagonale. Un<br \/>\nLa rondella \u00e8 fornita per sigillare la filettatura M16 x 1,5 durante l&#039;installazione. Questa rondella di tenuta \u00e8 sempre consigliata.<\/p>\n<p>PERICOLO \u2013 PRESTARE ATTENZIONE poich\u00e9 la fessura di scarico consentir\u00e0 il rilascio della pressione durante l&#039;allentamento del sistema idraulico di tensionamento dei cingoli, che potrebbe essere ad alta pressione. (Consultare il produttore dell&#039;attrezzatura). Indossare dispositivi di protezione individuale per evitare lesioni.<\/p>\n<p>INGRASSAGGIO \u2013 Per l\u2019ingrassaggio \u00e8 necessario utilizzare un raccordo ad alta pressione DIN da 22 mm<\/p>\n<p>FUNZIONAMENTO \u2013 Questo raccordo \u00e8 progettato per resistere a pressioni fino a 10.000 psi (69 MPa) durante il caricamento del sistema di tensionamento. Si consiglia di installare una valvola di non ritorno per proteggere le guarnizioni durante l&#039;utilizzo dei cingoli in ambienti difficili e su terreni irregolari.<\/p>\n<p>RIMOZIONE\/INSTALLAZIONE - Per rimuovere o installare utilizzare ESCLUSIVAMENTE una chiave esagonale da 27 mm.<\/p>\n<p>NON UTILIZZARE LA TESTA DEL RACCORDO O IL DIAMETRO DA 25 MM IN QUANTO CI\u00d2 POTREBBE COMPROMETTERE L&#039;INTEGRIT\u00c0 DEL GRUPPO.<\/p>\n<p>NON TENTARE DI SMONTARE QUESTO RACCORDO<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>HP2211316<\/p>","protected":false},"featured_media":4105,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[875,884,873],"product_tag":[],"class_list":["post-1083","product","type-product","status-publish","has-post-thumbnail","product_cat-mild-steel","product_cat-high-pressure-leakproof","product_cat-product-long","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple","berocket_lgv_grid","berocket_lgv_list_grid"],"acf":[],"_links":{"self":[{"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/product\/1083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/media\/4105"}],"wp:attachment":[{"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/media?parent=1083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/product_brand?post=1083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/product_cat?post=1083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kingfisherlubrication.co.uk\/it\/wp-json\/wp\/v2\/product_tag?post=1083"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}